{"id":2434,"date":"2025-09-13T10:47:24","date_gmt":"2025-09-13T10:47:24","guid":{"rendered":"https:\/\/nbaem.com\/?page_id=2434"},"modified":"2025-09-15T01:53:36","modified_gmt":"2025-09-15T01:53:36","slug":"magnets-used-in-renewable-energy","status":"publish","type":"page","link":"https:\/\/nbaem.com\/th\/magnets-used-in-renewable-energy\/","title":{"rendered":"\u0e43\u0e19\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19"},"content":{"rendered":"<style>* { box-sizing: border-box; } body {margin: 0;}*{box-sizing:border-box;}body{margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}#ijzj{background-image:url(\"https:\/\/nbaem.com\/wp-content\/uploads\/2025\/09\/Extruded-Neodymium-Magnets-for-Brushless-DC-Motors-1-e1757472737902.jpg\");max-width:100%;width:100%;}#i9vqx{max-width:100%;width:100%;}#iu3fj{max-width:100%;width:100%;}#iclu2k{max-width:100%;width:100%;}#ial8rt{max-width:100%;width:100%;}#iclgnd{max-width:100%;width:100%;}#iegpvg{max-width:100%;width:100%;}#iw2c1m{max-width:100%;width:100%;}#i8fu2x{max-width:100%;width:100%;}#ifl3ig{max-width:100%;width:100%;}#iqvhai{color:white;}#i5cyxu{color:white;}#iwarc4{color:white;}<\/style>\n<p><body><link href=\"https:\/\/cdn.jsdelivr.net\/npm\/tailwindcss@2.2.19\/dist\/tailwind.min.css\" rel=\"stylesheet\">\n<section id=\"ijzj\" class=\"relative bg-white h-screen bg-cover bg-center bg-no-repeat mb-0\" style=\"max-width: 100%; width: 100%;\">\n<div class=\"absolute inset-0 bg-[#025] bg-opacity-60\"><\/div>\n<div class=\"relative z-10 flex flex-col items-center justify-center h-full px-4 md:px-6 text-center text-white\">\n<h2 id=\"iwarc4\" class=\"text-4xl md:text-5xl lg:text-6xl font-bold mb-4\">\u0e40\u0e2d\u0e40\u0e2d\u0e47\u0e21\u0e1a\u0e35\u0e2d\u0e35\u0e40\u0e2d\u0e47\u0e21<\/h2>\n<p class=\"text-xl md:text-2xl mb-6 max-w-3xl\">\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e21\u0e32\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e08\u0e35\u0e19\u0e14\u0e49\u0e32\u0e19\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01<\/p>\n<p class=\"text-base md:text-lg mb-8 max-w-2xl\">\u0e2a\u0e48\u0e07\u0e21\u0e2d\u0e1a\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01<\/p>\n<div class=\"flex flex-col sm:flex-row gap-4\"><a href=\"https:\/\/nbaem.com\/th\/magnets-materials\/\" class=\"bg-white text-[#025] font-semibold py-3 px-6 rounded-lg hover:bg-gray-100 transition duration-300 focus:ring-2 focus:ring-white focus:ring-offset-2 focus:ring-offset-[#025] focus:outline-none\">\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32<\/a><a href=\"https:\/\/nbaem.com\/th\/contact-us\/\" class=\"border-2 border-white text-white font-semibold py-3 px-6 rounded-lg hover:bg-white hover:bg-opacity-20 transition duration-300 focus:ring-2 focus:ring-white focus:outline-none\">\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e40\u0e23\u0e32<\/a><\/div>\n<\/div>\n<\/section>\n<p><!--?xml encoding=\"UTF-8\"--><\/p>\n<section id=\"i9vqx\" class=\"bg-white mb-0\" style=\"max-width: 100%; width: 100%;\">\n<div class=\"container mx-auto px-6 py-20\">\n<div class=\"text-center mb-16\">\n<h2 class=\"text-3xl md:text-4xl font-bold text-[#025] mb-4\">\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19<\/h2>\n<p class=\"text-gray-600 max-w-3xl mx-auto\">NBAEM \u0e2a\u0e48\u0e07\u0e21\u0e2d\u0e1a\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e17\u0e35\u0e48\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e02\u0e2d\u0e07\u0e42\u0e25\u0e01\u0e2a\u0e39\u0e48\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19<\/p>\n<\/div>\n<div class=\"grid grid-cols-1 md:grid-cols-2 lg:grid-cols-3 gap-8 mb-16\"><!-- Wind Turbines --><\/p>\n<div class=\"bg-gray-50 rounded-lg overflow-hidden shadow-lg transition-transform duration-300 hover:transform hover:scale-105\">\n<div class=\"h-56 overflow-hidden\"><img decoding=\"async\" src=\"https:\/\/nbaem.com\/wp-content\/uploads\/2025\/09\/Siemens-direct-drive-turbine-4x2-750x375-1.webp\" alt=\"\u0e01\u0e31\u0e07\u0e2b\u0e31\u0e19\u0e25\u0e21\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e16\u0e32\u0e27\u0e23\" class=\"w-full h-full object-cover\"><\/div>\n<div class=\"p-6\">\n<h3 class=\"text-xl font-semibold text-[#025] mb-3\">\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e01\u0e31\u0e07\u0e2b\u0e31\u0e19\u0e25\u0e21<\/h3>\n<p class=\"text-gray-600\">\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e16\u0e32\u0e27\u0e23\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e40\u0e1a\u0e32\u0e01\u0e27\u0e48\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e41\u0e17\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e43\u0e19\u0e01\u0e31\u0e07\u0e2b\u0e31\u0e19\u0e25\u0e21\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e44\u0e14\u0e49<\/p>\n<\/div>\n<\/div>\n<p><!-- Electric Vehicles --><\/p>\n<div class=\"bg-gray-50 rounded-lg overflow-hidden shadow-lg transition-transform duration-300 hover:transform hover:scale-105\">\n<div class=\"h-56 overflow-hidden\"><img decoding=\"async\" src=\"https:\/\/nbaem.com\/wp-content\/uploads\/2025\/09\/electric-car-factory-us-GettyImages-1243051148-2400x1301-1.webp\" alt=\"\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\" class=\"w-full h-full object-cover\"><\/div>\n<div class=\"p-6\">\n<h3 class=\"text-xl font-semibold text-[#025] mb-3\">\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32<\/h3>\n<p class=\"text-gray-600\">\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01 NdFeB \u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e22\u0e37\u0e14\u0e23\u0e30\u0e22\u0e30\u0e17\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e19\u0e30\u0e42\u0e14\u0e22\u0e23\u0e27\u0e21<\/p>\n<\/div>\n<\/div>\n<p><!-- Magnetic Materials --><\/p>\n<div class=\"bg-gray-50 rounded-lg overflow-hidden shadow-lg transition-transform duration-300 hover:transform hover:scale-105\">\n<div class=\"h-56 overflow-hidden\"><img decoding=\"async\" src=\"https:\/\/nbaem.com\/wp-content\/uploads\/2025\/09\/Extruded-Neodymium-Magnets-for-Brushless-DC-Motors-1-e1757472737902.jpg\" alt=\"\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e19\u0e35\u0e42\u0e2d\u0e44\u0e14\u0e40\u0e21\u0e35\u0e22\u0e21\" class=\"w-full h-full object-cover\"><\/div>\n<div class=\"p-6\">\n<h3 class=\"text-xl font-semibold text-[#025] mb-3\">\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e02\u0e31\u0e49\u0e19\u0e2a\u0e39\u0e07<\/h3>\n<p class=\"text-gray-600\">NBAEM \u0e1c\u0e25\u0e34\u0e15\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e08\u0e32\u0e01\u0e41\u0e23\u0e48\u0e2b\u0e32\u0e22\u0e32\u0e01\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e2b\u0e32\u0e22\u0e32\u0e01\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19<\/p>\n<\/div>\n<\/div>\n<p><!-- Magnetic Generators --><\/p>\n<div class=\"bg-gray-50 rounded-lg overflow-hidden shadow-lg transition-transform duration-300 hover:transform hover:scale-105\">\n<div class=\"h-56 overflow-hidden\"><img decoding=\"async\" src=\"https:\/\/nbaem.com\/wp-content\/uploads\/2025\/09\/Wind-turbine.jpg\" alt=\"\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e16\u0e32\u0e27\u0e23\" class=\"w-full h-full object-cover\"><\/div>\n<div class=\"p-6\">\n<h3 class=\"text-xl font-semibold text-[#025] mb-3\">\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21<\/h3>\n<p class=\"text-gray-600\">\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2b\u0e25\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e16\u0e32\u0e27\u0e23\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e19\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e16\u0e37\u0e2d\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19<\/p>\n<\/div>\n<\/div>\n<p><!-- Thermoelectric --><\/p>\n<div class=\"bg-gray-50 rounded-lg overflow-hidden shadow-lg transition-transform duration-300 hover:transform hover:scale-105\">\n<div class=\"h-56 overflow-hidden\"><img decoding=\"async\" src=\"https:\/\/nbaem.com\/wp-content\/uploads\/2025\/09\/transverse-thermoelect.webp\" alt=\"\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e42\u0e21\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e34\u0e01\" class=\"w-full h-full object-cover\"><\/div>\n<div class=\"p-6\">\n<h3 class=\"text-xl font-semibold text-[#025] mb-3\">\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e42\u0e21\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e34\u0e01<\/h3>\n<p class=\"text-gray-600\">\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e42\u0e21\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e34\u0e01\u0e02\u0e31\u0e49\u0e19\u0e2a\u0e39\u0e07\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e40\u0e2a\u0e35\u0e22\u0e44\u0e1b\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49<\/p>\n<\/div>\n<\/div>\n<p><!-- Recycling --><\/p>\n<div class=\"bg-gray-50 rounded-lg overflow-hidden shadow-lg transition-transform duration-300 hover:transform hover:scale-105\">\n<div class=\"h-56 overflow-hidden\"><img decoding=\"async\" src=\"https:\/\/nbaem.com\/wp-content\/uploads\/2025\/09\/1-s2.0-S0921344924005573-ga1.jpg\" alt=\"\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e23\u0e35\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\" class=\"w-full h-full object-cover\"><\/div>\n<div class=\"p-6\">\n<h3 class=\"text-xl font-semibold text-[#025] mb-3\">\u0e01\u0e32\u0e23\u0e23\u0e35\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19<\/h3>\n<p class=\"text-gray-600\">NBAEM \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e23\u0e35\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25\u0e41\u0e1a\u0e1a\u0e1b\u0e34\u0e14\u0e27\u0e07\u0e08\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e41\u0e23\u0e48\u0e2b\u0e32\u0e22\u0e32\u0e01 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e41\u0e19\u0e48\u0e43\u0e08\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"bg-[#025] text-white rounded-lg p-8 md:p-12 flex flex-col md:flex-row items-center justify-between\">\n<div class=\"md:w-2\/3 mb-6 md:mb-0\">\n<h3 id=\"i5cyxu\" class=\"text-2xl md:text-3xl font-bold mb-4\">\u0e23\u0e48\u0e27\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e31\u0e19\u0e18\u0e21\u0e34\u0e15\u0e23\u0e01\u0e31\u0e1a NBAEM \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13<\/h3>\n<p class=\"text-white\/80\">\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e02\u0e31\u0e49\u0e19\u0e2a\u0e39\u0e07\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e21\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e2d\u0e1a\u0e2a\u0e19\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e21\u0e07\u0e27\u0e14\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48<\/p>\n<\/div>\n<div class=\"md:w-1\/3 text-center\"><a href=\"https:\/\/nbaem.com\/th\/contact-us\/\" class=\"inline-block bg-white text-[#025] font-semibold py-3 px-6 rounded-lg hover:bg-gray-100 transition-colors duration-300\">\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e40\u0e23\u0e32<\/a><\/div>\n<\/div>\n<\/div>\n<\/section>\n<p><!--?xml encoding=\"UTF-8\"--><\/p>\n<section id=\"iu3fj\" class=\"bg-gray-100 mb-0\" style=\"max-width: 100%; width: 100%;\">\n<div class=\"container mx-auto px-6 py-20\">\n<div class=\"text-center mb-16\">\n<h2 class=\"text-3xl md:text-4xl font-bold mb-4 text-[#025]\">\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19<\/h2>\n<p class=\"text-lg text-gray-700 max-w-3xl mx-auto\">NBAEM \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19<\/p>\n<\/div>\n<p><!-- Wind Power Section --><\/p>\n<div class=\"mb-20\">\n<div class=\"flex flex-col md:flex-row items-center gap-8 mb-8\">\n<div class=\"md:w-1\/2\">\n<h3 class=\"text-2xl font-bold text-[#025] mb-4\">\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e25\u0e21<\/h3>\n<p class=\"text-gray-700 mb-4\">\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e19\u0e35\u0e42\u0e2d\u0e14\u0e34\u0e21\u0e35\u0e22\u0e21\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e43\u0e2b\u0e49\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e01\u0e48\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e01\u0e31\u0e07\u0e2b\u0e31\u0e19\u0e25\u0e21\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e15\u0e47\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e16\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e41\u0e21\u0e49\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e23\u0e38\u0e19\u0e41\u0e23\u0e07<\/p>\n<ul class=\"list-disc list-inside text-gray-700 space-y-2 ml-4\">\n<li>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e16\u0e32\u0e27\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e31\u0e07\u0e2b\u0e31\u0e19\u0e25\u0e21\u0e41\u0e1a\u0e1a\u0e02\u0e31\u0e1a\u0e15\u0e23\u0e07<\/li>\n<li>\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e01\u0e30\u0e17\u0e31\u0e14\u0e23\u0e31\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e19\u0e32\u0e41\u0e19\u0e48\u0e19\u0e02\u0e2d\u0e07\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19<\/li>\n<li>\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e01\u0e31\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e43\u0e19\u0e17\u0e30\u0e40\u0e25<\/li>\n<li>\u0e23\u0e39\u0e1b\u0e17\u0e23\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e32\u0e14\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07\u0e44\u0e14\u0e49\u0e15\u0e32\u0e21\u0e02\u0e49\u0e2d\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15<\/li>\n<\/ul>\n<\/div>\n<div class=\"md:w-1\/2\"><img decoding=\"async\" id=\"i257ma\" src=\"https:\/\/nbaem.com\/wp-content\/uploads\/2025\/09\/Neodymium-Magnet-Wind-Turbines-e1757748816988.jpg\" alt=\"\u0e01\u0e31\u0e07\u0e2b\u0e31\u0e19\u0e25\u0e21\u0e17\u0e35\u0e48\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e14\u0e49\u0e27\u0e22\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e16\u0e32\u0e27\u0e23\" width=\"620\" class=\"rounded-lg shadow-lg w-full h-auto\"><\/div>\n<\/div>\n<\/div>\n<p><!-- Solar Energy Section --><\/p>\n<div class=\"mb-20\">\n<div class=\"flex flex-col md:flex-row-reverse items-center gap-8 mb-8\">\n<div class=\"md:w-1\/2\">\n<h3 class=\"text-2xl font-bold text-[#025] mb-4\">\u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c<\/h3>\n<p class=\"text-gray-700 mb-4\">NBAEM \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e34\u0e19\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e17\u0e19\u0e17\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e42\u0e1f\u0e42\u0e15\u0e42\u0e27\u0e25\u0e40\u0e17\u0e2d\u0e34\u0e01<\/p>\n<ul class=\"list-disc list-inside text-gray-700 space-y-2 ml-4\">\n<li>\u0e15\u0e31\u0e27\u0e02\u0e31\u0e1a\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e25\u0e44\u0e01\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c<\/li>\n<li>\u0e41\u0e01\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e34\u0e19\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e40\u0e0b\u0e25\u0e25\u0e4c<\/li>\n<li>\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e17\u0e19\u0e15\u0e48\u0e2d\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07<\/li>\n<li>\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e40\u0e1a\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e25\u0e14\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07<\/li>\n<\/ul>\n<\/div>\n<div class=\"md:w-1\/2\"><img decoding=\"async\" src=\"https:\/\/nbaem.com\/wp-content\/uploads\/2025\/09\/clean-energy-facility-solar-wind-e1757748931495.png\" alt=\"\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e41\u0e1c\u0e07\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e40\u0e0b\u0e25\u0e25\u0e4c\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\" width=\"600\" height=\"305\" class=\"rounded-lg shadow-lg w-full h-auto object-cover\"><\/div>\n<\/div>\n<\/div>\n<p><!-- Hydropower Section --><\/p>\n<div class=\"mb-20\">\n<div class=\"flex flex-col md:flex-row items-center gap-8 mb-8\">\n<div class=\"md:w-1\/2\">\n<h3 class=\"text-2xl font-bold text-[#025] mb-4\">\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1e\u0e25\u0e31\u0e07\u0e19\u0e49\u0e33<\/h3>\n<p class=\"text-gray-700 mb-4\">\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1e\u0e25\u0e31\u0e07\u0e19\u0e49\u0e33\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e19\u0e49\u0e2d\u0e22\u0e25\u0e07\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e22\u0e32\u0e27\u0e19\u0e32\u0e19\u0e02\u0e36\u0e49\u0e19<\/p>\n<ul class=\"list-disc list-inside text-gray-700 space-y-2 ml-4\">\n<li>\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e17\u0e35\u0e48\u0e17\u0e19\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e01\u0e31\u0e14\u0e01\u0e23\u0e48\u0e2d\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e43\u0e15\u0e49\u0e19\u0e49\u0e33<\/li>\n<li>\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e19\u0e32\u0e41\u0e19\u0e48\u0e19\u0e2a\u0e39\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e02\u0e19\u0e32\u0e14\u0e01\u0e30\u0e17\u0e31\u0e14\u0e23\u0e31\u0e14<\/li>\n<li>\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07\u0e44\u0e14\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23-\u0e1e\u0e25\u0e31\u0e07\u0e19\u0e49\u0e33\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48<\/li>\n<li>\u0e27\u0e07\u0e08\u0e23\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e33\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e07\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19<\/li>\n<\/ul>\n<\/div>\n<div class=\"md:w-1\/2\"><img decoding=\"async\" src=\"https:\/\/nbaem.com\/wp-content\/uploads\/2025\/09\/wind-power-permanent-magnet-generators-1-e1757749054188.jpeg\" alt=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e16\u0e32\u0e27\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e1e\u0e25\u0e31\u0e07\u0e19\u0e49\u0e33\" width=\"500\" height=\"360\" class=\"rounded-lg shadow-lg w-full h-auto object-cover\"><\/div>\n<\/div>\n<\/div>\n<p><!-- Emerging Technologies --><!-- CTA --><\/p>\n<div class=\"text-center mt-12\">\n<h3 class=\"text-xl font-bold text-[#025] mb-4\">\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19\u0e01\u0e31\u0e1a NBAEM \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13<\/h3>\n<p class=\"text-gray-700 mb-6 max-w-3xl mx-auto\">\u0e17\u0e35\u0e21\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e01\u0e31\u0e1a\u0e04\u0e38\u0e13\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e18\u0e35\u0e41\u0e01\u0e49\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07\u0e43\u0e2b\u0e49\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13<\/p>\n<p><a href=\"https:\/\/nbaem.com\/th\/contact-us\/\" class=\"inline-block bg-[#025] text-white font-semibold px-8 py-3 rounded-lg hover:bg-opacity-90 transition duration-300\">\u0e02\u0e2d\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32<\/a><\/div>\n<\/div>\n<\/section>\n<p><!--?xml encoding=\"UTF-8\"--><\/p>\n<section id=\"iclu2k\" class=\"bg-white mb-0\" style=\"max-width: 100%; width: 100%;\">\n<div class=\"container mx-auto px-6 py-20\"><!-- Header --><\/p>\n<div class=\"text-center mb-16\">\n<h2 class=\"text-4xl md:text-5xl font-bold text-gray-900 mb-4\">\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01<\/h2>\n<p class=\"text-xl text-gray-600 max-w-3xl mx-auto\">NBAEM \u0e40\u0e2a\u0e19\u0e2d\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e15\u0e48\u0e32\u0e07 \u0e46<\/p>\n<\/div>\n<p><!-- Main Categories Grid --><\/p>\n<div class=\"grid grid-cols-1 md:grid-cols-3 gap-8 mb-16\"><!-- Permanent Magnets --><\/p>\n<div class=\"bg-gray-50 rounded-lg overflow-hidden shadow-lg transition-transform duration-300 hover:shadow-xl hover:-translate-y-1\">\n<div class=\"h-64 overflow-hidden\"><img decoding=\"async\" src=\"https:\/\/nbaem.com\/wp-content\/uploads\/2025\/09\/Extruded-Neodymium-Magnets-for-Brushless-DC-Motors-1-e1757472737902.jpg\" alt=\"\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e16\u0e32\u0e27\u0e23\" class=\"w-full h-full object-cover\"><\/div>\n<div class=\"p-6\">\n<h3 class=\"text-2xl font-bold text-[#025] mb-3\">\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e16\u0e32\u0e27\u0e23<\/h3>\n<p class=\"text-gray-700 mb-4\">\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e17\u0e35\u0e48\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e44\u0e27\u0e49\u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u0e43\u0e2b\u0e49\u0e2a\u0e19\u0e32\u0e21\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e04\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07 \u0e46<\/p>\n<ul class=\"space-y-2 text-gray-700 mb-4\">\n<li class=\"flex items-start\">\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e19\u0e35\u0e42\u0e2d\u0e14\u0e34\u0e40\u0e21\u0e35\u0e22\u0e21 (NdFeB)<\/li>\n<li class=\"flex items-start\">\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e42\u0e04\u0e1a\u0e2d\u0e25\u0e15\u0e4c\u0e0b\u0e32\u0e42\u0e21\u0e40\u0e23\u0e35\u0e22\u0e21 (SmCo)<\/li>\n<li class=\"flex items-start\">\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e40\u0e1f\u0e2d\u0e44\u0e23\u0e15\u0e4c (\u0e40\u0e0b\u0e23\u0e32\u0e21\u0e34\u0e01)<\/li>\n<li class=\"flex items-start\">\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01 AlNiCo<\/li>\n<\/ul>\n<p><a href=\"https:\/\/nbaem.com\/th\/magnets-materials\/\" class=\"inline-block mt-2 px-6 py-2 bg-[#025] text-white font-medium rounded-md hover:bg-[#013366] transition-colors duration-300\">\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21<\/a><\/div>\n<\/div>\n<p><!-- Soft Magnetic Materials --><\/p>\n<div class=\"bg-gray-50 rounded-lg overflow-hidden shadow-lg transition-transform duration-300 hover:shadow-xl hover:-translate-y-1\">\n<div class=\"h-64 overflow-hidden\"><img decoding=\"async\" src=\"https:\/\/nbaem.com\/wp-content\/uploads\/2025\/09\/transverse-thermoelect.webp\" alt=\"\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e2d\u0e48\u0e2d\u0e19\" class=\"w-full h-full object-cover\"><\/div>\n<div class=\"p-6\">\n<h3 class=\"text-2xl font-bold text-[#025] mb-3\">\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e2d\u0e48\u0e2d\u0e19<\/h3>\n<p class=\"text-gray-700 mb-4\">\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e16\u0e2d\u0e14\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e32\u0e21\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e44\u0e14\u0e49<\/p>\n<ul class=\"space-y-2 text-gray-700 mb-4\">\n<li class=\"flex items-start\"><span id=\"itn5g1\">\u0e41\u0e1c\u0e48\u0e19\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e0b\u0e34\u0e25\u0e34\u0e04\u0e2d\u0e19\u0e01\u0e25\u0e32\u0e2a<\/span><\/li>\n<li class=\"flex items-start\">\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e44\u0e23\u0e15\u0e4c\u0e2d\u0e48\u0e2d\u0e19<\/li>\n<li class=\"flex items-start\">Permalloy (\u0e42\u0e25\u0e2b\u0e30\u0e1c\u0e2a\u0e21 Ni-Fe)<\/li>\n<li class=\"flex items-start\">\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e30\u0e21\u0e2d\u0e23\u0e4c\u0e1f\u0e31\u0e2a\u0e41\u0e25\u0e30\u0e19\u0e32\u0e42\u0e19\u0e04\u0e23\u0e34\u0e2a\u0e15\u0e31\u0e25\u0e25\u0e34\u0e19<\/li>\n<\/ul>\n<p><a href=\"https:\/\/nbaem.com\/th\/products\/lamination-core\/\" class=\"inline-block mt-2 px-6 py-2 bg-[#025] text-white font-medium rounded-md hover:bg-[#013366] transition-colors duration-300\">\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21<\/a><\/div>\n<\/div>\n<p><!-- Magnetic Assemblies --><\/p>\n<div class=\"bg-gray-50 rounded-lg overflow-hidden shadow-lg transition-transform duration-300 hover:shadow-xl hover:-translate-y-1\">\n<div class=\"h-64 overflow-hidden\"><img decoding=\"async\" src=\"https:\/\/nbaem.com\/wp-content\/uploads\/2025\/09\/Xnip2025-09-12_09-55-12.jpg\" alt=\"\u0e0a\u0e38\u0e14\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e41\u0e25\u0e30\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\" class=\"w-full h-full object-cover\"><\/div>\n<div class=\"p-6\">\n<h3 class=\"text-2xl font-bold text-[#025] mb-3\">\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01<\/h3>\n<p class=\"text-gray-700 mb-4\">\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e1c\u0e2a\u0e21\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e01\u0e31\u0e1a\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e37\u0e48\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e40\u0e09\u0e1e\u0e32\u0e30<\/p>\n<ul class=\"space-y-2 text-gray-700 mb-4\">\n<li class=\"flex items-start\">\u0e42\u0e23\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e40\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01<\/li>\n<li class=\"flex items-start\">\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01<\/li>\n<li class=\"flex items-start\">\u0e40\u0e0b\u0e47\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01<\/li>\n<li class=\"flex items-start\">\u0e40\u0e01\u0e23\u0e32\u0e30\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e22\u0e36\u0e14\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01<\/li>\n<\/ul>\n<p><a href=\"https:\/\/nbaem.com\/th\/magnet-assembly\/\" class=\"inline-block mt-2 px-6 py-2 bg-[#025] text-white font-medium rounded-md hover:bg-[#013366] transition-colors duration-300\">\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<p><!--?xml encoding=\"UTF-8\"--><\/p>\n<section id=\"ial8rt\" class=\"bg-gray-100 mb-0\" style=\"max-width: 100%; width: 100%;\">\n<div class=\"container mx-auto px-6 py-20\"><!-- Header --><\/p>\n<div class=\"text-center mb-16\">\n<h2 class=\"text-3xl md:text-4xl font-bold text-[#025] mb-4\">\u0e17\u0e33\u0e44\u0e21\u0e40\u0e25\u0e37\u0e2d\u0e01 NBAEM \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19<\/h2>\n<p class=\"text-gray-600 max-w-3xl mx-auto\">\u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 NBAEM \u0e21\u0e2d\u0e1a\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e17\u0e35\u0e48\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e17\u0e35\u0e48\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e02\u0e2d\u0e07\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01<\/p>\n<\/div>\n<p><!-- Features Grid --><\/p>\n<div class=\"grid grid-cols-1 md:grid-cols-2 lg:grid-cols-3 gap-8 mb-16\"><!-- Feature 1 --><\/p>\n<div class=\"bg-white rounded-lg shadow-md overflow-hidden transition-transform duration-300 hover:transform hover:scale-105\">\n<div class=\"h-48 overflow-hidden\"><img decoding=\"async\" src=\"https:\/\/nbaem.com\/wp-content\/uploads\/2025\/09\/pmg-permanent-magnet-generator-wind-turbines-1030x687-1.webp\" alt=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e01\u0e31\u0e07\u0e2b\u0e31\u0e19\u0e25\u0e21\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e16\u0e32\u0e27\u0e23\" class=\"w-full h-full object-cover\"><\/div>\n<div class=\"p-6\">\n<h3 class=\"text-xl font-semibold text-[#025] mb-3\">\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e25\u0e34\u0e28\u0e14\u0e49\u0e32\u0e19\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e25\u0e21<\/h3>\n<p class=\"text-gray-600\">\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e16\u0e32\u0e27\u0e23\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e31\u0e07\u0e2b\u0e31\u0e19\u0e25\u0e21 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e21\u0e49\u0e43\u0e19\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e25\u0e21\u0e15\u0e48\u0e33<\/p>\n<\/div>\n<\/div>\n<p><!-- Feature 2 --><\/p>\n<div class=\"bg-white rounded-lg shadow-md overflow-hidden transition-transform duration-300 hover:transform hover:scale-105\">\n<div class=\"h-48 overflow-hidden\"><img decoding=\"async\" src=\"https:\/\/nbaem.com\/wp-content\/uploads\/2025\/09\/electric-car-factory-us-GettyImages-1243051148-2400x1301-1.jpg\" alt=\"\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\" class=\"w-full h-full object-cover\"><\/div>\n<div class=\"p-6\">\n<h3 class=\"text-xl font-semibold text-[#025] mb-3\">\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32<\/h3>\n<p class=\"text-gray-600\">\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01 NBAEM \u0e43\u0e2b\u0e49\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2b\u0e19\u0e32\u0e41\u0e19\u0e48\u0e19\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e16\u0e35\u0e22\u0e23\u0e20\u0e32\u0e1e\u0e17\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e01\u0e27\u0e48\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e23\u0e30\u0e22\u0e30\u0e17\u0e32\u0e07\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e<\/p>\n<\/div>\n<\/div>\n<p><!-- Feature 3 --><\/p>\n<div class=\"bg-white rounded-lg shadow-md overflow-hidden transition-transform duration-300 hover:transform hover:scale-105\">\n<div class=\"h-48 overflow-hidden\"><img decoding=\"async\" src=\"https:\/\/nbaem.com\/wp-content\/uploads\/2025\/09\/Xnip2025-09-13_15-42-45.jpg\" alt=\"\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\" class=\"w-full h-full object-cover\"><\/div>\n<div class=\"p-6\">\n<h3 class=\"text-xl font-semibold text-[#025] mb-3\">\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c<\/h3>\n<p class=\"text-gray-600\">\u0e41\u0e01\u0e19\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e19\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e16\u0e37\u0e2d\u0e02\u0e2d\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01<\/p>\n<\/div>\n<\/div>\n<p><!-- Feature 4 --><\/p>\n<div class=\"bg-white rounded-lg shadow-md overflow-hidden transition-transform duration-300 hover:transform hover:scale-105\">\n<div class=\"h-48 overflow-hidden\"><img decoding=\"async\" src=\"https:\/\/nbaem.com\/wp-content\/uploads\/2025\/09\/CMM.jpg\" alt=\"\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e07\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\" class=\"w-full h-full object-cover\"><\/div>\n<div class=\"p-6\">\n<h3 class=\"text-xl font-semibold text-[#025] mb-3\">\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e02\u0e31\u0e49\u0e19\u0e2a\u0e39\u0e07<\/h3>\n<p class=\"text-gray-600\">\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e23\u0e48\u0e2b\u0e32\u0e22\u0e32\u0e01\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e41\u0e23\u0e48\u0e2b\u0e32\u0e22\u0e32\u0e01 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e25\u0e49\u0e33\u0e2a\u0e21\u0e31\u0e22\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e43\u0e2b\u0e21\u0e48<\/p>\n<\/div>\n<\/div>\n<p><!-- Feature 5 --><\/p>\n<div class=\"bg-white rounded-lg shadow-md overflow-hidden transition-transform duration-300 hover:transform hover:scale-105\">\n<div class=\"h-48 overflow-hidden\"><img decoding=\"async\" src=\"https:\/\/nbaem.com\/wp-content\/uploads\/2025\/09\/1716974589-normal-wind-turbines.webp\" alt=\"\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e25\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2b\u0e25\u0e32\u0e22\u0e01\u0e31\u0e07\u0e2b\u0e31\u0e19\" class=\"w-full h-full object-cover\"><\/div>\n<div class=\"p-6\">\n<h3 class=\"text-xl font-semibold text-[#025] mb-3\">\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e<\/h3>\n<p class=\"text-gray-600\">\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 ISO \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e02\u0e49\u0e21\u0e07\u0e27\u0e14 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e41\u0e19\u0e48\u0e43\u0e08\u0e27\u0e48\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e21\u0e07\u0e27\u0e14\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19<\/p>\n<\/div>\n<\/div>\n<p><!-- Feature 6 --><\/p>\n<div class=\"bg-white rounded-lg shadow-md overflow-hidden transition-transform duration-300 hover:transform hover:scale-105\">\n<div class=\"h-48 overflow-hidden\"><img decoding=\"async\" src=\"https:\/\/nbaem.com\/wp-content\/uploads\/2025\/09\/How-Electricity-Generation-Works.webp\" alt=\"\u0e41\u0e1c\u0e19\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32\" class=\"w-full h-full object-cover\"><\/div>\n<div class=\"p-6\">\n<h3 class=\"text-xl font-semibold text-[#025] mb-3\">\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19<\/h3>\n<p class=\"text-gray-600\">NBAEM \u0e21\u0e38\u0e48\u0e07\u0e21\u0e31\u0e48\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e35\u0e48\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e15\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e42\u0e14\u0e22\u0e25\u0e14\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e21\u0e35\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e23\u0e35\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25\u0e02\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15<\/p>\n<\/div>\n<\/div>\n<\/div>\n<p><!-- CTA Section --><\/p>\n<div class=\"bg-[#025] text-white rounded-lg p-8 md:p-12 text-center\">\n<h3 id=\"iqvhai\" class=\"text-2xl md:text-3xl font-bold mb-4\">\u0e23\u0e48\u0e27\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e31\u0e19\u0e18\u0e21\u0e34\u0e15\u0e23\u0e01\u0e31\u0e1a NBAEM \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13<\/h3>\n<p class=\"mb-8 max-w-3xl mx-auto\">\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e41\u0e1a\u0e1a\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e40\u0e2d\u0e07\u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e23\u0e32\u0e22\u0e34\u0e19\u0e14\u0e35\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e14\u0e49\u0e32\u0e19\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e<\/p>\n<div class=\"flex flex-col sm:flex-row justify-center gap-4\"><a href=\"#contact\" class=\"inline-block bg-white text-[#025] font-semibold px-6 py-3 rounded-lg hover:bg-gray-100 transition-colors duration-300\">\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32<\/a><\/div>\n<\/div>\n<\/div>\n<\/section>\n<p><!--?xml encoding=\"UTF-8\"--><\/p>\n<section id=\"iclgnd\" class=\"bg-white py-12 mb-0\" style=\"max-width: 100%; width: 100%;\">\n<div class=\"container mx-auto px-6 py-20\">\n<div class=\"text-center mb-16\">\n<h2 class=\"text-3xl font-extrabold text-gray-800 mb-4\">\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e02\u0e2d\u0e07\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 NBAEM<\/h2>\n<p class=\"text-gray-600\">\u0e2d\u0e48\u0e32\u0e19\u0e27\u0e34\u0e18\u0e35\u0e17\u0e35\u0e48\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e02\u0e2d\u0e07 NBAEM \u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e23\u0e25\u0e38\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32<\/p>\n<\/div>\n<div class=\"grid grid-cols-1 md:grid-cols-2 lg:grid-cols-3 gap-8\"><!-- Case Study 1 --><\/p>\n<div class=\"bg-white shadow-md rounded-lg overflow-hidden\"><img decoding=\"async\" src=\"https:\/\/nbaem.com\/wp-content\/uploads\/2025\/09\/Application_of_Neodymium_Magnets_in_Wind_Turbine_Generators-1.webp\" alt=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e01\u0e31\u0e07\u0e2b\u0e31\u0e19\u0e25\u0e21\" class=\"w-full h-56 object-cover object-center\"><\/p>\n<div class=\"p-6\">\n<h3 class=\"text-xl font-semibold text-gray-800 mb-2\">\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e01\u0e31\u0e07\u0e2b\u0e31\u0e19\u0e25\u0e21<\/h3>\n<p class=\"text-gray-600 mb-4\">\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e27\u0e48\u0e32\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e02\u0e2d\u0e07 NBAEM \u0e0a\u0e48\u0e27\u0e22\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e01\u0e31\u0e07\u0e2b\u0e31\u0e19\u0e25\u0e21\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33 \u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e43\u0e2b\u0e49\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e02\u0e36\u0e49\u0e19 15%<\/p>\n<\/div>\n<\/div>\n<p><!-- Case Study 2 --><\/p>\n<div class=\"bg-white shadow-md rounded-lg overflow-hidden\"><img decoding=\"async\" src=\"https:\/\/nbaem.com\/wp-content\/uploads\/2025\/09\/electric-car-factory-us-GettyImages-1243051148-2400x1301-1.jpg\" alt=\"\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\" class=\"w-full h-56 object-cover object-center\"><\/p>\n<div class=\"p-6\">\n<h3 class=\"text-xl font-semibold text-gray-800 mb-2\">\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e02\u0e2d\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32<\/h3>\n<p class=\"text-gray-600 mb-4\">\u0e04\u0e49\u0e19\u0e1e\u0e1a\u0e27\u0e48\u0e32\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e02\u0e31\u0e49\u0e19\u0e2a\u0e39\u0e07\u0e02\u0e2d\u0e07 NBAEM \u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1a\u0e40\u0e1a\u0e32\u0e25\u0e07\u0e41\u0e25\u0e30\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e23\u0e32\u0e22\u0e43\u0e2b\u0e0d\u0e48<\/p>\n<\/div>\n<\/div>\n<p><!-- Case Study 3 --><\/p>\n<div class=\"bg-white shadow-md rounded-lg overflow-hidden\"><img decoding=\"async\" src=\"https:\/\/nbaem.com\/wp-content\/uploads\/2025\/09\/modern-assembly-line-manufacturing-electric-motors-cutting-edge-technology-sophisticated-producing-using-advanced-rare-367108665.webp\" alt=\"\u0e2a\u0e32\u0e22\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\" class=\"w-full h-56 object-cover object-center\"><\/p>\n<div class=\"p-6\">\n<h3 class=\"text-xl font-semibold text-gray-800 mb-2\">\u0e1b\u0e0f\u0e34\u0e27\u0e31\u0e15\u0e34\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21<\/h3>\n<p class=\"text-gray-600 mb-4\">\u0e14\u0e39\u0e27\u0e48\u0e32 NBAEM \u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33\u0e25\u0e14\u0e02\u0e19\u0e32\u0e14\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e19\u0e32\u0e41\u0e19\u0e48\u0e19\u0e02\u0e2d\u0e07\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e14\u0e49\u0e27\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"mt-12 text-center\">\n<p class=\"text-gray-600\">\u0e2d\u0e22\u0e32\u0e01\u0e23\u0e39\u0e49\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e27\u0e48\u0e32 NBAEM \u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23?<\/p>\n<p><a href=\"#\" class=\"inline-block mt-4 px-6 py-3 bg-indigo-600 text-white font-semibold rounded-md hover:bg-indigo-700 focus:outline-none focus:ring-2 focus:ring-indigo-500 focus:ring-opacity-50\">\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e40\u0e23\u0e32<\/a><\/div>\n<\/div>\n<\/section>\n<p><!--?xml encoding=\"UTF-8\"--><\/p>\n<section id=\"iegpvg\" class=\"bg-gray-100 mb-0\" style=\"max-width: 100%; width: 100%;\">\n<div class=\"container mx-auto px-6 py-20\">\n<div class=\"mb-12 text-center\">\n<h2 class=\"mb-4 text-3xl font-bold text-[#025] md:text-4xl\">\u0e04\u0e33\u0e16\u0e32\u0e21\u0e17\u0e35\u0e48\u0e1e\u0e1a\u0e1a\u0e48\u0e2d\u0e22<\/h2>\n<p class=\"mx-auto max-w-3xl text-gray-600\">\u0e04\u0e49\u0e19\u0e2b\u0e32\u0e04\u0e33\u0e15\u0e2d\u0e1a\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e33\u0e16\u0e32\u0e21\u0e17\u0e35\u0e48\u0e1e\u0e1a\u0e1a\u0e48\u0e2d\u0e22\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e02\u0e2d\u0e07 NBAEM \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32<\/p>\n<\/div>\n<div class=\"mx-auto max-w-4xl divide-y divide-gray-200 rounded-xl bg-white p-4 shadow-lg md:p-8\">\n<div class=\"py-5\">\n<details class=\"group\">NBAEM \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e43\u0e14\u0e1a\u0e49\u0e32\u0e07?<br \/>\n&gt;<\/p>\n<p class=\"mt-3 text-gray-600\">NBAEM \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 Neodymium (NdFeB), Samarium Cobalt (SmCo), Ferrite, \u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01 AlNiCo \u0e41\u0e25\u0e30\u0e0a\u0e38\u0e14\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e41\u0e1a\u0e1a\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e40\u0e2d\u0e07 \u0e40\u0e23\u0e32\u0e21\u0e35\u0e40\u0e01\u0e23\u0e14\u0e41\u0e25\u0e30\u0e2a\u0e40\u0e1b\u0e04\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19<\/p>\n<\/details>\n<\/div>\n<div class=\"py-5\">\n<details class=\"group\">\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e43\u0e14\u0e1a\u0e49\u0e32\u0e07\u0e17\u0e35\u0e48\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23?<br \/>\n&gt;<\/p>\n<p class=\"mt-3 text-gray-600\">\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2b\u0e25\u0e32\u0e22\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19 (\u0e01\u0e31\u0e07\u0e2b\u0e31\u0e19\u0e25\u0e21, \u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e40\u0e0b\u0e25\u0e25\u0e4c), \u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c, \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c, \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c, \u0e2d\u0e27\u0e01\u0e32\u0e28, \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21, \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e41\u0e25\u0e30\u0e2d\u0e35\u0e01\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22<\/p>\n<\/details>\n<\/div>\n<div class=\"py-5\">\n<details class=\"group\">NBAEM \u0e21\u0e35\u0e43\u0e1a\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e2d\u0e30\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07?<br \/>\n&gt;<\/p>\n<p class=\"mt-3 text-gray-600\">NBAEM \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07 ISO 9001:2015 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e40\u0e23\u0e32\u0e22\u0e31\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e32\u0e21 RoHS, REACH \u0e41\u0e25\u0e30\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e2a\u0e32\u0e01\u0e25\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e21\u0e35\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e31\u0e49\u0e19\u0e2a\u0e39\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e41\u0e19\u0e48\u0e43\u0e08\u0e27\u0e48\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e34\u0e49\u0e19\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e01\u0e34\u0e19\u0e01\u0e27\u0e48\u0e32\u0e02\u0e49\u0e2d\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21<\/p>\n<\/details>\n<\/div>\n<div class=\"py-5\">\n<details class=\"group\">\u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e31\u0e49\u0e19\u0e15\u0e48\u0e33 (MOQ) \u0e04\u0e37\u0e2d\u0e40\u0e17\u0e48\u0e32\u0e44\u0e2b\u0e23\u0e48?<br \/>\n&gt;<\/p>\n<p class=\"mt-3 text-gray-600\">MOQ \u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19\u0e44\u0e1b\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e40\u0e1b\u0e04 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e40\u0e23\u0e32\u0e21\u0e31\u0e01\u0e23\u0e31\u0e1a\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32\u0e44\u0e14\u0e49 \u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e41\u0e1a\u0e1a\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e40\u0e2d\u0e07\u0e2d\u0e32\u0e08\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e08\u0e33\u0e19\u0e27\u0e19\u0e02\u0e31\u0e49\u0e19\u0e15\u0e48\u0e33\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e01\u0e23\u0e38\u0e13\u0e32\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e17\u0e35\u0e21\u0e02\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 MOQ \u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23<\/p>\n<\/details>\n<\/div>\n<div class=\"py-5\">\n<details class=\"group\">\u0e40\u0e27\u0e25\u0e32\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e19\u0e32\u0e19\u0e40\u0e17\u0e48\u0e32\u0e44\u0e2b\u0e23\u0e48?<br \/>\n&gt;<\/p>\n<p class=\"mt-3 text-gray-600\">\u0e40\u0e27\u0e25\u0e32\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e21\u0e31\u0e01\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 2-3 \u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e22\u0e37\u0e19\u0e22\u0e31\u0e19\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e40\u0e2d\u0e07\u0e2d\u0e32\u0e08\u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 4-6 \u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c \u0e40\u0e23\u0e32\u0e22\u0e31\u0e07\u0e21\u0e35\u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e14\u0e48\u0e27\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e40\u0e23\u0e48\u0e07\u0e14\u0e48\u0e27\u0e19 \u0e17\u0e35\u0e21\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e17\u0e33\u0e07\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e41\u0e19\u0e48\u0e43\u0e08\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e21\u0e2d\u0e1a\u0e15\u0e23\u0e07\u0e40\u0e27\u0e25\u0e32\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01<\/p>\n<\/details>\n<\/div>\n<div class=\"py-5\">\n<details class=\"group\">\u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e2b\u0e49\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e41\u0e1a\u0e1a\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e40\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e44\u0e2b\u0e21?<br \/>\n&gt;<\/p>\n<p class=\"mt-3 text-gray-600\">\u0e43\u0e0a\u0e48, NBAEM \u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e14\u0e49\u0e32\u0e19\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e41\u0e1a\u0e1a\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e40\u0e2d\u0e07 \u0e17\u0e35\u0e21\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e33\u0e07\u0e32\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e2a\u0e40\u0e1b\u0e04\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e41\u0e25\u0e30\u0e0a\u0e38\u0e14\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13 \u0e40\u0e23\u0e32\u0e21\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0a\u0e48\u0e27\u0e22\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a, \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e15\u0e49\u0e19\u0e41\u0e1a\u0e1a, \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e15\u0e47\u0e21\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e15\u0e23\u0e07\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13<\/p>\n<\/details>\n<\/div>\n<\/div>\n<div class=\"mt-12 text-center\">\n<p class=\"mb-6 text-gray-600\">\u0e44\u0e21\u0e48\u0e1e\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e01\u0e33\u0e25\u0e31\u0e07\u0e21\u0e2d\u0e07\u0e2b\u0e32\u0e43\u0e0a\u0e48\u0e44\u0e2b\u0e21?<\/p>\n<p><a href=\"#contact\" class=\"inline-block rounded-md bg-[#025] px-6 py-3 text-white transition-colors hover:bg-[#014] focus:outline-none focus:ring-2 focus:ring-[#025] focus:ring-offset-2\">\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e17\u0e35\u0e21\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32<\/a><\/div>\n<\/div>\n<\/section>\n<p><!--?xml encoding=\"UTF-8\"--><\/p>\n<section id=\"iw2c1m\" class=\"bg-white mb-0\" style=\"max-width: 100%; width: 100%;\">\n<div class=\"container mx-auto px-6 py-20\">\n<div class=\"text-center mb-12\">\n<h2 class=\"text-3xl md:text-4xl font-bold text-[#025] mb-4\">\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07<\/h2>\n<p class=\"text-gray-600 max-w-3xl mx-auto\">\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14 \u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e0a\u0e34\u0e07\u0e25\u0e36\u0e01\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e15\u0e48\u0e32\u0e07 \u0e46<\/p>\n<\/div>\n<div class=\"grid grid-cols-1 md:grid-cols-2 lg:grid-cols-3 gap-8\"><!-- Article 1 --><\/p>\n<div class=\"bg-white rounded-lg shadow-md overflow-hidden border border-gray-200 hover:shadow-lg transition-shadow duration-300\">\n<div class=\"h-48 overflow-hidden\"><img decoding=\"async\" src=\"https:\/\/nbaem.com\/wp-content\/uploads\/2025\/09\/modern-assembly-line-manufacturing-electric-motors-cutting-edge-technology-sophisticated-producing-using-advanced-rare-367108665.webp\" alt=\"\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\" class=\"w-full h-full object-cover\"><\/div>\n<div class=\"p-6\">\n<h3 class=\"font-bold text-xl mb-2 text-[#025]\">\u0e04\u0e27\u0e32\u0e21\u0e01\u0e49\u0e32\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e43\u0e19\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32<\/h3>\n<p class=\"text-gray-600 mb-4\">\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e27\u0e48\u0e32\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e01\u0e33\u0e25\u0e31\u0e07\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23<\/p>\n<p><a href=\"https:\/\/nbaem.com\/th\/magnetic-materials-in-motor-technology\/\" target=\"_blank\" rel=\"noopener noreferrer\" class=\"inline-block text-[#025] font-medium hover:underline\">\u0e2d\u0e48\u0e32\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21 \u2192<\/a><\/div>\n<\/div>\n<p><!-- Article 2 --><\/p>\n<div class=\"bg-white rounded-lg shadow-md overflow-hidden border border-gray-200 hover:shadow-lg transition-shadow duration-300\">\n<div class=\"h-48 overflow-hidden\"><img decoding=\"async\" src=\"https:\/\/nbaem.com\/wp-content\/uploads\/2025\/09\/servo-motor-structure.jpg\" alt=\"\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e44\u0e1a\u0e19\u0e4c\u0e25\u0e21\" class=\"w-full h-full object-cover\"><\/div>\n<div class=\"p-6\">\n<h3 class=\"font-bold text-xl mb-2 text-[#025]\">\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e16\u0e32\u0e27\u0e23\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e01\u0e31\u0e07\u0e2b\u0e31\u0e19\u0e25\u0e21<\/h3>\n<p class=\"text-gray-600 mb-4\">\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e27\u0e48\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e16\u0e32\u0e27\u0e23\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e19\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e16\u0e37\u0e2d\u0e02\u0e2d\u0e07\u0e01\u0e31\u0e07\u0e2b\u0e31\u0e19\u0e25\u0e21\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23<\/p>\n<p><a href=\"https:\/\/nbaem.com\/th\/magnets-in-wind-turbines\/\" target=\"_blank\" class=\"inline-block text-[#025] font-medium hover:underline\">\u0e2d\u0e48\u0e32\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21 \u2192<\/a><\/div>\n<\/div>\n<p><!-- Article 3 --><\/p>\n<div class=\"bg-white rounded-lg shadow-md overflow-hidden border border-gray-200 hover:shadow-lg transition-shadow duration-300\">\n<div class=\"h-48 overflow-hidden\"><img decoding=\"async\" src=\"https:\/\/nbaem.com\/wp-content\/uploads\/2025\/09\/mri-magnetic-resonance-imaging-machine-epitomizing-role-cutting-edge-medical-technology-healthcare-critical-291606166.jpg\" alt=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 MRI\" class=\"w-full h-full object-cover\"><\/div>\n<div class=\"p-6\">\n<h3 class=\"font-bold text-xl mb-2 text-[#025]\">\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e43\u0e19\u0e20\u0e32\u0e1e\u0e16\u0e48\u0e32\u0e22\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c<\/h3>\n<p class=\"text-gray-600 mb-4\">\u0e04\u0e49\u0e19\u0e1e\u0e1a\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e43\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 MRI \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c<\/p>\n<p><a href=\"https:\/\/nbaem.com\/th\/magnetic-materials-in-medical-imaging\/\" target=\"_blank\" class=\"inline-block text-[#025] font-medium hover:underline\">\u0e2d\u0e48\u0e32\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21 \u2192<\/a><\/div>\n<\/div>\n<p><!-- Article 4 --><\/p>\n<div class=\"bg-white rounded-lg shadow-md overflow-hidden border border-gray-200 hover:shadow-lg transition-shadow duration-300\">\n<div class=\"h-48 overflow-hidden\"><img decoding=\"async\" src=\"https:\/\/nbaem.com\/wp-content\/uploads\/2025\/09\/Noema_GreenEnergy_R2_V3b.webp\" alt=\"\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27\" class=\"w-full h-full object-cover\"><\/div>\n<div class=\"p-6\">\n<h3 class=\"font-bold text-xl mb-2 text-[#025]\">\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19<\/h3>\n<p class=\"text-gray-600 mb-4\">\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e43\u0e19\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e34\u0e15\u0e23\u0e15\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48<\/p>\n<p><a href=\"https:\/\/nbaem.com\/th\/sustainable-magnets-for-green-energy\/\" target=\"_blank\" class=\"inline-block text-[#025] font-medium hover:underline\">\u0e2d\u0e48\u0e32\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21 \u2192<\/a><\/div>\n<\/div>\n<p><!-- Article 5 --><\/p>\n<div class=\"bg-white rounded-lg shadow-md overflow-hidden border border-gray-200 hover:shadow-lg transition-shadow duration-300\">\n<div class=\"h-48 overflow-hidden\"><img decoding=\"async\" src=\"https:\/\/nbaem.com\/wp-content\/uploads\/2025\/09\/wave_park.webp\" alt=\"\u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e04\u0e25\u0e37\u0e48\u0e19\" class=\"w-full h-full object-cover\"><\/div>\n<div class=\"p-6\">\n<h3 class=\"font-bold text-xl mb-2 text-[#025]\">\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e04\u0e25\u0e37\u0e48\u0e19<\/h3>\n<p class=\"text-gray-600 mb-4\">\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e27\u0e48\u0e32\u0e17\u0e33\u0e44\u0e21\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07\u0e08\u0e36\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e1b\u0e25\u0e07\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e04\u0e25\u0e37\u0e48\u0e19\u0e17\u0e30\u0e40\u0e25\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19<\/p>\n<p><a href=\"https:\/\/nbaem.com\/th\/magnetic-solutions-for-wave-energy-systems\/\" target=\"_blank\" class=\"inline-block text-[#025] font-medium hover:underline\">\u0e2d\u0e48\u0e32\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21 \u2192<\/a><\/div>\n<\/div>\n<p><!-- Article 6 --><\/p>\n<div class=\"bg-white rounded-lg shadow-md overflow-hidden border border-gray-200 hover:shadow-lg transition-shadow duration-300\">\n<div class=\"h-48 overflow-hidden\"><img decoding=\"async\" src=\"https:\/\/nbaem.com\/wp-content\/uploads\/2025\/09\/30845061_magnetic-autocontrol-microdrive-battery-backup-and-solar-power-supply-24v_2_657617-1-scaled.jpg\" alt=\"\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e32\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\" class=\"w-full h-full object-cover\"><\/div>\n<div class=\"p-6\">\n<h3 class=\"font-bold text-xl mb-2 text-[#025]\">\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e02\u0e31\u0e49\u0e19\u0e2a\u0e39\u0e07\u0e43\u0e19\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22<\/h3>\n<p class=\"text-gray-600 mb-4\">\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e01\u0e49\u0e32\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e14\u0e49\u0e27\u0e22\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e2d\u0e2d\u0e01<\/p>\n<p><a href=\"https:\/\/nbaem.com\/th\/advanced-magnetic-systems-in-security-applications\/\" target=\"_blank\" class=\"inline-block text-[#025] font-medium hover:underline\">\u0e2d\u0e48\u0e32\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21 \u2192<\/a><\/div>\n<\/div>\n<\/div>\n<div class=\"text-center mt-12\"><a href=\"https:\/\/nbaem.com\/th\/blog\/\" class=\"inline-block bg-[#025] text-white font-semibold px-6 py-3 rounded-md hover:bg-opacity-90 transition-colors duration-300\">\u0e14\u0e39\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14<\/a><\/div>\n<\/div>\n<\/section>\n<p><!--?xml encoding=\"UTF-8\"--><\/p>\n<section id=\"i8fu2x\" class=\"bg-gray-100 mb-0\" style=\"max-width: 100%; width: 100%;\">\n<div class=\"container mx-auto px-6 py-20\">\n<div class=\"flex flex-col md:flex-row items-center justify-between gap-12\">\n<div class=\"w-full md:w-1\/2 space-y-6\">\n<h2 class=\"text-3xl md:text-4xl font-bold text-[#025]\">\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e07?<\/h2>\n<p class=\"text-gray-700 text-lg\">NBAEM \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33\u0e08\u0e32\u0e01\u0e08\u0e35\u0e19\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01 \u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e0a\u0e31\u0e49\u0e19\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e23\u0e07\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e04\u0e23\u0e31\u0e49\u0e07\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13<\/p>\n<p class=\"text-gray-700\">\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e17\u0e31\u0e19\u0e17\u0e35\u0e44\u0e2b\u0e21? \u0e42\u0e17\u0e23\u0e2b\u0e32\u0e40\u0e23\u0e32\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 <a href=\"tel:+86-18757483467\" class=\"text-[#025] font-bold hover:underline\">+86-18757483467<\/a> \u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e35\u0e40\u0e21\u0e25 <a href=\"mailto:info@nbaem.com\" class=\"text-[#025] font-bold hover:underline\">info@nbaem.com<\/a><\/p>\n<p><a href=\"https:\/\/nbaem.com\/th\/contact-us\/\" class=\"w-full\"><button type=\"submit\" class=\"w-full bg-[#025] text-white py-3 px-6 rounded-md hover:bg-[#036] transition duration-300 font-medium\">\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32<\/button><\/a><\/div>\n<div class=\"w-full md:w-1\/2 space-y-6\">\n<div class=\"relative rounded-lg overflow-hidden shadow-xl\"><img decoding=\"async\" src=\"https:\/\/nbaem.com\/wp-content\/uploads\/2025\/09\/Neodymium-Magnet-Wind-Turbines-1.webp\" alt=\"\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e43\u0e19\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19\" class=\"w-full h-auto object-cover\"><\/p>\n<div class=\"absolute inset-0 bg-gradient-to-t from-[#025]\/80 to-transparent flex items-end\">\n<p class=\"text-white p-4 font-medium\">\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e02\u0e31\u0e49\u0e19\u0e2a\u0e39\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19<\/p>\n<\/div>\n<\/div>\n<div class=\"grid grid-cols-2 gap-4\">\n<div class=\"bg-white p-4 rounded-lg shadow-md\">\n<h3 class=\"font-bold text-[#025] mb-2\">\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01<\/h3>\n<p class=\"text-gray-600 text-sm\">\u0e2a\u0e48\u0e07\u0e14\u0e48\u0e27\u0e19\u0e16\u0e36\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01<\/p>\n<\/div>\n<div class=\"bg-white p-4 rounded-lg shadow-md\">\n<h3 class=\"font-bold text-[#025] mb-2\">\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e41\u0e1a\u0e1a\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e40\u0e2d\u0e07<\/h3>\n<p class=\"text-gray-600 text-sm\">\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13<\/p>\n<\/div>\n<div class=\"bg-white p-4 rounded-lg shadow-md\">\n<h3 class=\"font-bold text-[#025] mb-2\">\u0e1d\u0e48\u0e32\u0e22\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e17\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04<\/h3>\n<p class=\"text-gray-600 text-sm\">\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d<\/p>\n<\/div>\n<div class=\"bg-white p-4 rounded-lg shadow-md\">\n<h3 class=\"font-bold text-[#025] mb-2\">\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07<\/h3>\n<p class=\"text-gray-600 text-sm\">\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07 ISO<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"mt-16 text-center\"><\/div>\n<\/div>\n<\/section>\n<p><!--?xml encoding=\"UTF-8\"--><\/p>\n<section id=\"ifl3ig\" class=\"bg-white text-gray-800 border-t border-gray-200 mb-0\" style=\"max-width: 100%; width: 100%;\">\n<div class=\"container mx-auto px-6 py-20\"><!-- Footer top section with logo and quick intro --><\/p>\n<div class=\"grid grid-cols-1 md:grid-cols-4 gap-8 mb-8\">\n<div class=\"col-span-1 md:col-span-1\">\n<div class=\"flex flex-col\">\n<h2 class=\"text-2xl font-bold text-[#025] mb-4\">\u0e40\u0e2d\u0e40\u0e2d\u0e47\u0e21\u0e1a\u0e35\u0e2d\u0e35\u0e40\u0e2d\u0e47\u0e21<\/h2>\n<p class=\"text-sm mb-4\">\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e08\u0e35\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01\u0e41\u0e25\u0e30\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/nbaem.com\/wp-content\/uploads\/2025\/09\/Arnold-Around-the-World-1024x511-1.webp\" alt=\"\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e0f\u0e15\u0e31\u0e27\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e42\u0e25\u0e01\u0e02\u0e2d\u0e07 NBAEM\" class=\"w-full max-w-[220px] h-auto rounded-md mb-4\"><\/div>\n<\/div>\n<p><!-- Products column --><\/p>\n<div class=\"col-span-1\">\n<h3 class=\"text-lg font-semibold text-[#025] mb-4\">\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32<\/h3>\n<ul class=\"space-y-2\">\n<li><a href=\"\/th\/neodymium-magnets\/\" class=\"text-gray-600 hover:text-[#025] transition\">\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e19\u0e35\u0e42\u0e2d\u0e14\u0e34\u0e21\u0e34\u0e22\u0e21<\/a><\/li>\n<li><a href=\"https:\/\/nbaem.com\/th\/products\/ceramic-magnet\/\" class=\"text-gray-600 hover:text-[#025] transition\">\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e44\u0e23\u0e15\u0e4c<\/a><\/li>\n<li><a href=\"https:\/\/nbaem.com\/th\/products\/samarium-cobalt-magnets\/\" class=\"text-gray-600 hover:text-[#025] transition\">\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01 SmCo<\/a><\/li>\n<li><a href=\"https:\/\/nbaem.com\/th\/products\/alnico-magnet\/\" class=\"text-gray-600 hover:text-[#025] transition\">\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01 AlNiCo<\/a><\/li>\n<li><a href=\"https:\/\/nbaem.com\/th\/magnet-assembly\/\" class=\"text-gray-600 hover:text-[#025] transition\">\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01<\/a><\/li>\n<\/ul>\n<\/div>\n<p><!-- Industries column --><\/p>\n<div class=\"col-span-1\">\n<h3 class=\"text-lg font-semibold text-[#025] mb-4\">\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21<\/h3>\n<ul class=\"space-y-2\">\n<li><a href=\"https:\/\/nbaem.com\/th\/magnet-used-in-electric-vehicles\/\" class=\"text-gray-600 hover:text-[#025] transition\">\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c<\/a><\/li>\n<li><a href=\"https:\/\/nbaem.com\/th\/magnets-used-in-medical\/\" class=\"text-gray-600 hover:text-[#025] transition\">\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c<\/a><\/li>\n<li><a href=\"https:\/\/nbaem.com\/th\/magnets-used-in-renewable-energy\/\" class=\"text-gray-600 hover:text-[#025] transition\">\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19<\/a><\/li>\n<li><a href=\"https:\/\/nbaem.com\/th\/magnets-used-in-consumer-electronics\/\" class=\"text-gray-600 hover:text-[#025] transition\">\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c<\/a><\/li>\n<li><a href=\"https:\/\/nbaem.com\/th\/magnets-used-in-industrial\/\" class=\"text-gray-600 hover:text-[#025] transition\">\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21<\/a><\/li>\n<\/ul>\n<\/div>\n<p><!-- Contact column --><\/p>\n<div class=\"col-span-1\">\n<h3 class=\"text-lg font-semibold text-[#025] mb-4\">\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e40\u0e23\u0e32<\/h3>\n<address class=\"not-italic text-gray-600 mb-4\">\n<p id=\"i5rzyr\">\u0e0b\u0e2d\u0e22 15 \u0e16\u0e19\u0e19\u0e2b\u0e07\u0e29\u0e4c\u0e40\u0e2a\u0e47\u0e07 \u0e2b\u0e07\u0e15\u0e31\u0e07<br \/>\n\u0e19\u0e04\u0e23\u0e19\u0e34\u0e48\u0e07\u0e42\u0e1b\u0e4b \u0e21\u0e13\u0e11\u0e25\u0e40\u0e08\u0e49\u0e2d\u0e40\u0e08\u0e35\u0e22\u0e07 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e08\u0e35\u0e19<\/p>\n<\/address>\n<div class=\"mb-4\">\n<p class=\"mb-1\"><span class=\"font-semibold\">\u0e2d\u0e35\u0e40\u0e21\u0e25:<\/span> <a href=\"mailto:info@nbaem.com\" class=\"text-gray-600 hover:text-[#025]\">info@nbaem.com<\/a><\/p>\n<p id=\"i2fa0u\"><span class=\"font-semibold\">\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c:<\/span> <a href=\"tel:+86123456789\" class=\"text-gray-600 hover:text-[#025]\">+86 1<\/a>8757483467<\/p>\n<\/div>\n<div class=\"flex space-x-4\"><\/div>\n<\/div>\n<\/div>\n<p><!-- Quick links for SEO --><\/p>\n<div class=\"border-t border-gray-200 pt-8 mb-8\">\n<div class=\"grid grid-cols-2 md:grid-cols-4 gap-4\">\n<div>\n<h4 class=\"text-sm font-semibold text-[#025] mb-2\">\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23<\/h4>\n<ul class=\"text-xs space-y-1\">\n<li><a href=\"\/th\/blog\/\" class=\"text-gray-600 hover:text-[#025]\">\u0e1a\u0e25\u0e47\u0e2d\u0e01<\/a><\/li>\n<\/ul>\n<\/div>\n<div>\n<h4 class=\"text-sm font-semibold text-[#025] mb-2\">\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19<\/h4>\n<ul class=\"text-xs space-y-1\">\n<li><a href=\"https:\/\/nbaem.com\/th\/contact-us\/\" class=\"text-gray-600 hover:text-[#025]\">\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e1d\u0e48\u0e32\u0e22\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19<\/a><\/li>\n<\/ul>\n<\/div>\n<div>\n<h4 class=\"text-sm font-semibold text-[#025] mb-2\">\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17<\/h4>\n<ul class=\"text-xs space-y-1\">\n<li><a href=\"\/th\/about-us\/\" class=\"text-gray-600 hover:text-[#025]\">\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e23\u0e32<\/a><\/li>\n<\/ul>\n<\/div>\n<div>\n<h4 class=\"text-sm font-semibold text-[#025] mb-2\">\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22<\/h4>\n<ul class=\"text-xs space-y-1\">\n<li><a href=\"\/th\/privacy-policy\/\" class=\"text-gray-600 hover:text-[#025]\">\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27<\/a><\/li>\n<li>\n<li><\/ul>\n<\/div>\n<\/div>\n<\/div>\n<p><!-- Applications & Certifications --><\/p>\n<div class=\"border-t border-gray-200 pt-8 mb-8\">\n<div class=\"grid grid-cols-1 md:grid-cols-2 gap-8\">\n<div>\n<h3 class=\"text-lg font-semibold text-[#025] mb-4\">\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19<\/h3>\n<div class=\"grid grid-cols-2 gap-4\">\n<div class=\"flex items-center\"><img decoding=\"async\" src=\"https:\/\/nbaem.com\/wp-content\/uploads\/2025\/09\/mri-magnetic-resonance-imaging-machine-epitomizing-role-cutting-edge-medical-technology-healthcare-critical-291606166.jpg\" alt=\"\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 MRI \u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\" class=\"w-16 h-16 object-cover rounded mr-2\"><span class=\"text-sm\">\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c<\/span><\/div>\n<div class=\"flex items-center\"><img decoding=\"async\" src=\"https:\/\/nbaem.com\/wp-content\/uploads\/2025\/09\/this-changes-everything-monumental-fusion-breakthrough-as-magnet-levitates-100000-ton-aircraft-carrier-paving-way-for-iter-assembly.webp\" alt=\"\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\" class=\"w-16 h-16 object-cover rounded mr-2\"><span class=\"text-sm\">\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19<\/span><\/div>\n<div class=\"flex items-center\"><img decoding=\"async\" src=\"https:\/\/nbaem.com\/wp-content\/uploads\/2025\/09\/1495533044_big_eogen.webp\" alt=\"\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\" class=\"w-16 h-16 object-cover rounded mr-2\"><span class=\"text-sm\">\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21<\/span><\/div>\n<div class=\"flex items-center\"><img decoding=\"async\" src=\"https:\/\/nbaem.com\/wp-content\/uploads\/2025\/09\/30845061_magnetic-autocontrol-microdrive-battery-backup-and-solar-power-supply-24v_2_657617-1-scaled.webp\" alt=\"\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\" class=\"w-16 h-16 object-cover rounded mr-2\"><span class=\"text-sm\">\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22<\/span><\/div>\n<\/div>\n<\/div>\n<div>\n<h3 class=\"text-lg font-semibold text-[#025] mb-4\">\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19<\/h3>\n<div class=\"flex flex-wrap gap-4\">\n<div class=\"flex items-center border border-gray-200 rounded px-3 py-2\"><span class=\"text-sm font-medium\">\u0e44\u0e2d\u0e40\u0e2d\u0e2a\u0e42\u0e2d 9001<\/span><\/div>\n<div class=\"flex items-center border border-gray-200 rounded px-3 py-2\"><span class=\"text-sm font-medium\">\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 ISO 14001<\/span><\/div>\n<div class=\"flex items-center border border-gray-200 rounded px-3 py-2\"><span class=\"text-sm font-medium\">\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 TS 16949<\/span><\/div>\n<div class=\"flex items-center border border-gray-200 rounded px-3 py-2\"><span class=\"text-sm font-medium\">\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 RoHS<\/span><\/div>\n<div class=\"flex items-center border border-gray-200 rounded px-3 py-2\"><span class=\"text-sm font-medium\">\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 REACH<\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><!-- Footer bottom --><\/p>\n<div class=\"border-t border-gray-200 pt-6\"><\/div>\n<\/div>\n<\/section>\n<p><!-- End AIVB Required Assets --><!-- End AIVB Required Assets --><!-- End AIVB Required Assets --><!-- End AIVB Required Assets --><!-- End AIVB Required Assets --><!-- End AIVB Required Assets --><!-- End AIVB Required Assets --><!-- End AIVB Required Assets --><\/body><\/p>\n<p><!-- AIVB Required Assets -->\n<link rel=\"stylesheet\" href=\"https:\/\/cdn.jsdelivr.net\/npm\/tailwindcss@4.1.12\/index.min.css\">\n<link rel=\"stylesheet\" href=\"https:\/\/cdn.jsdelivr.net\/npm\/@fortawesome\/fontawesome-free@6.4.0\/css\/all.min.css\">\n<script src=\"https:\/\/cdn.tailwindcss.com\"><\/script><br \/>\n<!-- End AIVB Required Assets --><\/p>","protected":false},"excerpt":{"rendered":"<p>NBAEM \u0e1c\u0e39\u0e49\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e08\u0e35\u0e19\u0e14\u0e49\u0e32\u0e19\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u0e2a\u0e48\u0e07\u0e21\u0e2d\u0e1a\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01 \u0e2a\u0e33\u0e23\u0e27\u0e08\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e40\u0e23\u0e32 \u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19 NBAEM \u0e2a\u0e48\u0e07\u0e21\u0e2d\u0e1a\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e17\u0e35\u0e48\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e42\u0e25\u0e01\u0e2a\u0e39\u0e48\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e01\u0e31\u0e07\u0e2b\u0e31\u0e19\u0e25\u0e21 \u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e16\u0e32\u0e27\u0e23\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e40\u0e1a\u0e32\u0e41\u0e1a\u0e1a\u0e02\u0e31\u0e1a\u0e15\u0e23\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e02\u0e08\u0e31\u0e14[\u2026]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_mi_skip_tracking":false,"footnotes":""},"class_list":["post-2434","page","type-page","status-publish","hentry"],"rankMath":{"parentDomain":"nbaem.com","noFollowDomains":[],"noFollowExcludeDomains":[],"noFollowExternalLinks":false,"featuredImageNotice":"The featured image should be at least 200 by 200 pixels to be picked up by Facebook and other social media sites.","pluginReviewed":false,"postSettings":{"linkSuggestions":true,"useFocusKeyword":false},"frontEndScore":false,"postName":"magnets-used-in-renewable-energy","permalinkFormat":"https:\/\/nbaem.com\/th\/%pagename%\/","showLockModifiedDate":true,"assessor":{"focusKeywordLink":"https:\/\/nbaem.com\/wp-admin\/edit.php?focus_keyword=%focus_keyword%&post_type=%post_type%","hasTOCPlugin":{"luckywp-table-of-contents\/luckywp-table-of-contents.php":"LuckyWP \u0e2a\u0e32\u0e23\u0e1a\u0e31\u0e0d"},"primaryTaxonomy":false,"serpData":{"title":"","description":"","focusKeywords":"permanent magnet generator for wind turbine","pillarContent":false,"canonicalUrl":"","breadcrumbTitle":"","advancedRobots":[],"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":"","facebookHasOverlay":false,"facebookImageOverlay":"","facebookAuthor":"","twitterCardType":"","twitterUseFacebook":true,"twitterTitle":"","twitterDescription":"","twitterImage":"","twitterImageID":"","twitterHasOverlay":false,"twitterImageOverlay":"","twitterPlayerUrl":"","twitterPlayerSize":"","twitterPlayerStream":"","twitterPlayerStreamCtype":"","twitterAppDescription":"","twitterAppIphoneName":"","twitterAppIphoneID":"","twitterAppIphoneUrl":"","twitterAppIpadName":"","twitterAppIpadID":"","twitterAppIpadUrl":"","twitterAppGoogleplayName":"","twitterAppGoogleplayID":"","twitterAppGoogleplayUrl":"","twitterAppCountry":"","robots":{"index":true},"twitterAuthor":"username","primaryTerm":0,"authorName":"nbaem01","titleTemplate":"%title% %page% %sep% %sitename%","descriptionTemplate":"","showScoreFrontend":true,"lockModifiedDate":false},"powerWords":[],"diacritics":{"A":"[\\u0041\\u24B6\\uFF21\\u00C0\\u00C1\\u00C2\\u1EA6\\u1EA4\\u1EAA\\u1EA8\\u00C3\\u0100\\u0102\\u1EB0\\u1EAE\\u1EB4\\u1EB2\\u0226\\u01E0\\u00C4\\u01DE\\u1EA2\\u00C5\\u01FA\\u01CD\\u0200\\u0202\\u1EA0\\u1EAC\\u1EB6\\u1E00\\u0104\\u023A\\u2C6F]","AA":"[\\uA732]","AE":"[\\u00C6\\u01FC\\u01E2]","AO":"[\\uA734]","AU":"[\\uA736]","AV":"[\\uA738\\uA73A]","AY":"[\\uA73C]","B":"[\\u0042\\u24B7\\uFF22\\u1E02\\u1E04\\u1E06\\u0243\\u0182\\u0181]","C":"[\\u0043\\u24B8\\uFF23\\u0106\\u0108\\u010A\\u010C\\u00C7\\u1E08\\u0187\\u023B\\uA73E]","D":"[\\u0044\\u24B9\\uFF24\\u1E0A\\u010E\\u1E0C\\u1E10\\u1E12\\u1E0E\\u0110\\u018B\\u018A\\u0189\\uA779]","DZ":"[\\u01F1\\u01C4]","Dz":"[\\u01F2\\u01C5]","E":"[\\u0045\\u24BA\\uFF25\\u00C8\\u00C9\\u00CA\\u1EC0\\u1EBE\\u1EC4\\u1EC2\\u1EBC\\u0112\\u1E14\\u1E16\\u0114\\u0116\\u00CB\\u1EBA\\u011A\\u0204\\u0206\\u1EB8\\u1EC6\\u0228\\u1E1C\\u0118\\u1E18\\u1E1A\\u0190\\u018E]","F":"[\\u0046\\u24BB\\uFF26\\u1E1E\\u0191\\uA77B]","G":"[\\u0047\\u24BC\\uFF27\\u01F4\\u011C\\u1E20\\u011E\\u0120\\u01E6\\u0122\\u01E4\\u0193\\uA7A0\\uA77D\\uA77E]","H":"[\\u0048\\u24BD\\uFF28\\u0124\\u1E22\\u1E26\\u021E\\u1E24\\u1E28\\u1E2A\\u0126\\u2C67\\u2C75\\uA78D]","I":"[\\u0049\\u24BE\\uFF29\\u00CC\\u00CD\\u00CE\\u0128\\u012A\\u012C\\u0130\\u00CF\\u1E2E\\u1EC8\\u01CF\\u0208\\u020A\\u1ECA\\u012E\\u1E2C\\u0197]","J":"[\\u004A\\u24BF\\uFF2A\\u0134\\u0248]","K":"[\\u004B\\u24C0\\uFF2B\\u1E30\\u01E8\\u1E32\\u0136\\u1E34\\u0198\\u2C69\\uA740\\uA742\\uA744\\uA7A2]","L":"[\\u004C\\u24C1\\uFF2C\\u013F\\u0139\\u013D\\u1E36\\u1E38\\u013B\\u1E3C\\u1E3A\\u0141\\u023D\\u2C62\\u2C60\\uA748\\uA746\\uA780]","LJ":"[\\u01C7]","Lj":"[\\u01C8]","M":"[\\u004D\\u24C2\\uFF2D\\u1E3E\\u1E40\\u1E42\\u2C6E\\u019C]","N":"[\\u004E\\u24C3\\uFF2E\\u01F8\\u0143\\u00D1\\u1E44\\u0147\\u1E46\\u0145\\u1E4A\\u1E48\\u0220\\u019D\\uA790\\uA7A4]","NJ":"[\\u01CA]","Nj":"[\\u01CB]","O":"[\\u004F\\u24C4\\uFF2F\\u00D2\\u00D3\\u00D4\\u1ED2\\u1ED0\\u1ED6\\u1ED4\\u00D5\\u1E4C\\u022C\\u1E4E\\u014C\\u1E50\\u1E52\\u014E\\u022E\\u0230\\u00D6\\u022A\\u1ECE\\u0150\\u01D1\\u020C\\u020E\\u01A0\\u1EDC\\u1EDA\\u1EE0\\u1EDE\\u1EE2\\u1ECC\\u1ED8\\u01EA\\u01EC\\u00D8\\u01FE\\u0186\\u019F\\uA74A\\uA74C]","OI":"[\\u01A2]","OO":"[\\uA74E]","OU":"[\\u0222]","P":"[\\u0050\\u24C5\\uFF30\\u1E54\\u1E56\\u01A4\\u2C63\\uA750\\uA752\\uA754]","Q":"[\\u0051\\u24C6\\uFF31\\uA756\\uA758\\u024A]","R":"[\\u0052\\u24C7\\uFF32\\u0154\\u1E58\\u0158\\u0210\\u0212\\u1E5A\\u1E5C\\u0156\\u1E5E\\u024C\\u2C64\\uA75A\\uA7A6\\uA782]","S":"[\\u0053\\u24C8\\uFF33\\u1E9E\\u015A\\u1E64\\u015C\\u1E60\\u0160\\u1E66\\u1E62\\u1E68\\u0218\\u015E\\u2C7E\\uA7A8\\uA784]","T":"[\\u0054\\u24C9\\uFF34\\u1E6A\\u0164\\u1E6C\\u021A\\u0162\\u1E70\\u1E6E\\u0166\\u01AC\\u01AE\\u023E\\uA786]","TZ":"[\\uA728]","U":"[\\u0055\\u24CA\\uFF35\\u00D9\\u00DA\\u00DB\\u0168\\u1E78\\u016A\\u1E7A\\u016C\\u00DC\\u01DB\\u01D7\\u01D5\\u01D9\\u1EE6\\u016E\\u0170\\u01D3\\u0214\\u0216\\u01AF\\u1EEA\\u1EE8\\u1EEE\\u1EEC\\u1EF0\\u1EE4\\u1E72\\u0172\\u1E76\\u1E74\\u0244]","V":"[\\u0056\\u24CB\\uFF36\\u1E7C\\u1E7E\\u01B2\\uA75E\\u0245]","VY":"[\\uA760]","W":"[\\u0057\\u24CC\\uFF37\\u1E80\\u1E82\\u0174\\u1E86\\u1E84\\u1E88\\u2C72]","X":"[\\u0058\\u24CD\\uFF38\\u1E8A\\u1E8C]","Y":"[\\u0059\\u24CE\\uFF39\\u1EF2\\u00DD\\u0176\\u1EF8\\u0232\\u1E8E\\u0178\\u1EF6\\u1EF4\\u01B3\\u024E\\u1EFE]","Z":"[\\u005A\\u24CF\\uFF3A\\u0179\\u1E90\\u017B\\u017D\\u1E92\\u1E94\\u01B5\\u0224\\u2C7F\\u2C6B\\uA762]","a":"[\\u0061\\u24D0\\uFF41\\u1E9A\\u00E0\\u00E1\\u00E2\\u1EA7\\u1EA5\\u1EAB\\u1EA9\\u00E3\\u0101\\u0103\\u1EB1\\u1EAF\\u1EB5\\u1EB3\\u0227\\u01E1\\u00E4\\u01DF\\u1EA3\\u00E5\\u01FB\\u01CE\\u0201\\u0203\\u1EA1\\u1EAD\\u1EB7\\u1E01\\u0105\\u2C65\\u0250]","aa":"[\\uA733]","ae":"[\\u00E6\\u01FD\\u01E3]","ao":"[\\uA735]","au":"[\\uA737]","av":"[\\uA739\\uA73B]","ay":"[\\uA73D]","b":"[\\u0062\\u24D1\\uFF42\\u1E03\\u1E05\\u1E07\\u0180\\u0183\\u0253]","c":"[\\u0063\\u24D2\\uFF43\\u0107\\u0109\\u010B\\u010D\\u00E7\\u1E09\\u0188\\u023C\\uA73F\\u2184]","d":"[\\u0064\\u24D3\\uFF44\\u1E0B\\u010F\\u1E0D\\u1E11\\u1E13\\u1E0F\\u0111\\u018C\\u0256\\u0257\\uA77A]","dz":"[\\u01F3\\u01C6]","e":"[\\u0065\\u24D4\\uFF45\\u00E8\\u00E9\\u00EA\\u1EC1\\u1EBF\\u1EC5\\u1EC3\\u1EBD\\u0113\\u1E15\\u1E17\\u0115\\u0117\\u00EB\\u1EBB\\u011B\\u0205\\u0207\\u1EB9\\u1EC7\\u0229\\u1E1D\\u0119\\u1E19\\u1E1B\\u0247\\u025B\\u01DD]","f":"[\\u0066\\u24D5\\uFF46\\u1E1F\\u0192\\uA77C]","g":"[\\u0067\\u24D6\\uFF47\\u01F5\\u011D\\u1E21\\u011F\\u0121\\u01E7\\u0123\\u01E5\\u0260\\uA7A1\\u1D79\\uA77F]","h":"[\\u0068\\u24D7\\uFF48\\u0125\\u1E23\\u1E27\\u021F\\u1E25\\u1E29\\u1E2B\\u1E96\\u0127\\u2C68\\u2C76\\u0265]","hv":"[\\u0195]","i":"[\\u0069\\u24D8\\uFF49\\u00EC\\u00ED\\u00EE\\u0129\\u012B\\u012D\\u00EF\\u1E2F\\u1EC9\\u01D0\\u0209\\u020B\\u1ECB\\u012F\\u1E2D\\u0268\\u0131]","j":"[\\u006A\\u24D9\\uFF4A\\u0135\\u01F0\\u0249]","k":"[\\u006B\\u24DA\\uFF4B\\u1E31\\u01E9\\u1E33\\u0137\\u1E35\\u0199\\u2C6A\\uA741\\uA743\\uA745\\uA7A3]","l":"[\\u006C\\u24DB\\uFF4C\\u0140\\u013A\\u013E\\u1E37\\u1E39\\u013C\\u1E3D\\u1E3B\\u017F\\u0142\\u019A\\u026B\\u2C61\\uA749\\uA781\\uA747]","lj":"[\\u01C9]","m":"[\\u006D\\u24DC\\uFF4D\\u1E3F\\u1E41\\u1E43\\u0271\\u026F]","n":"[\\u006E\\u24DD\\uFF4E\\u01F9\\u0144\\u00F1\\u1E45\\u0148\\u1E47\\u0146\\u1E4B\\u1E49\\u019E\\u0272\\u0149\\uA791\\uA7A5]","nj":"[\\u01CC]","o":"[\\u006F\\u24DE\\uFF4F\\u00F2\\u00F3\\u00F4\\u1ED3\\u1ED1\\u1ED7\\u1ED5\\u00F5\\u1E4D\\u022D\\u1E4F\\u014D\\u1E51\\u1E53\\u014F\\u022F\\u0231\\u00F6\\u022B\\u1ECF\\u0151\\u01D2\\u020D\\u020F\\u01A1\\u1EDD\\u1EDB\\u1EE1\\u1EDF\\u1EE3\\u1ECD\\u1ED9\\u01EB\\u01ED\\u00F8\\u01FF\\u0254\\uA74B\\uA74D\\u0275]","oi":"[\\u01A3]","ou":"[\\u0223]","oo":"[\\uA74F]","p":"[\\u0070\\u24DF\\uFF50\\u1E55\\u1E57\\u01A5\\u1D7D\\uA751\\uA753\\uA755]","q":"[\\u0071\\u24E0\\uFF51\\u024B\\uA757\\uA759]","r":"[\\u0072\\u24E1\\uFF52\\u0155\\u1E59\\u0159\\u0211\\u0213\\u1E5B\\u1E5D\\u0157\\u1E5F\\u024D\\u027D\\uA75B\\uA7A7\\uA783]","s":"[\\u0073\\u24E2\\uFF53\\u015B\\u1E65\\u015D\\u1E61\\u0161\\u1E67\\u1E63\\u1E69\\u0219\\u015F\\u023F\\uA7A9\\uA785\\u1E9B]","ss":"[\\u00DF]","t":"[\\u0074\\u24E3\\uFF54\\u1E6B\\u1E97\\u0165\\u1E6D\\u021B\\u0163\\u1E71\\u1E6F\\u0167\\u01AD\\u0288\\u2C66\\uA787]","tz":"[\\uA729]","u":"[\\u0075\\u24E4\\uFF55\\u00F9\\u00FA\\u00FB\\u0169\\u1E79\\u016B\\u1E7B\\u016D\\u00FC\\u01DC\\u01D8\\u01D6\\u01DA\\u1EE7\\u016F\\u0171\\u01D4\\u0215\\u0217\\u01B0\\u1EEB\\u1EE9\\u1EEF\\u1EED\\u1EF1\\u1EE5\\u1E73\\u0173\\u1E77\\u1E75\\u0289]","v":"[\\u0076\\u24E5\\uFF56\\u1E7D\\u1E7F\\u028B\\uA75F\\u028C]","vy":"[\\uA761]","w":"[\\u0077\\u24E6\\uFF57\\u1E81\\u1E83\\u0175\\u1E87\\u1E85\\u1E98\\u1E89\\u2C73]","x":"[\\u0078\\u24E7\\uFF58\\u1E8B\\u1E8D]","y":"[\\u0079\\u24E8\\uFF59\\u1EF3\\u00FD\\u0177\\u1EF9\\u0233\\u1E8F\\u00FF\\u1EF7\\u1E99\\u1EF5\\u01B4\\u024F\\u1EFF]","z":"[\\u007A\\u24E9\\uFF5A\\u017A\\u1E91\\u017C\\u017E\\u1E93\\u1E95\\u01B6\\u0225\\u0240\\u2C6C\\uA763]"},"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasRedirection":true,"hasBreadcrumb":true},"homeUrl":"https:\/\/nbaem.com\/th","objectID":2434,"objectType":"post","locale":"th","localeFull":"th","overlayImages":{"play":{"name":"Play icon","url":"https:\/\/nbaem.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","path":"\/home\/u209265392\/domains\/nbaem.com\/public_html\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","position":"middle_center"},"gif":{"name":"GIF icon","url":"https:\/\/nbaem.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","path":"\/home\/u209265392\/domains\/nbaem.com\/public_html\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","position":"middle_center"}},"defautOgImage":"https:\/\/nbaem.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/social-placeholder.jpg","customPermalinks":true,"isUserRegistered":false,"autoSuggestKeywords":false,"connectSiteUrl":"https:\/\/rankmath.com\/auth?site=https%3A%2F%2Fnbaem.com%2Fth&r=https%3A%2F%2Fnbaem.com%2Fth%2Fwp-json%2Fwp%2Fv2%2Fpages%2F2434%3Fnonce%3D7ee2e77523","maxTags":5,"trendsIcon":"<svg viewBox=\"0 0 610 610\"><path d=\"M18.85,446,174.32,290.48l58.08,58.08L76.93,504a14.54,14.54,0,0,1-20.55,0L18.83,466.48a14.54,14.54,0,0,1,0-20.55Z\" style=\"fill:#4285f4\"\/><path d=\"M242.65,242.66,377.59,377.6l-47.75,47.75a14.54,14.54,0,0,1-20.55,0L174.37,290.43l47.75-47.75A14.52,14.52,0,0,1,242.65,242.66Z\" style=\"fill:#ea4335\"\/><polygon points=\"319.53 319.53 479.26 159.8 537.34 217.88 377.61 377.62 319.53 319.53\" style=\"fill:#fabb05\"\/><path d=\"M594.26,262.73V118.61h0a16.94,16.94,0,0,0-16.94-16.94H433.2a16.94,16.94,0,0,0-12,28.92L565.34,274.71h0a16.94,16.94,0,0,0,28.92-12Z\" style=\"fill:#34a853\"\/><rect width=\"610\" height=\"610\" style=\"fill:none\"\/><\/svg>","showScore":true,"siteFavIcon":"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAQCAYAAAAf8\/9hAAABs0lEQVR4AWL4\/\/8\/RRjO8Iucx+noO0MWUDo16FYABMGP6ZfUcRnWtm27jVPbtm3bttuH2t3eFPcY9pLz7NxiLjCyVd87pKnHyqXyxtCs8APd0rnyxiu4qSeA3QEDrAwBDrT1s1Rc\/OrjLZwqVmOSu6+Lamcpp2KKMA9PH1BYXMe1mUP5qotvXTywsOEEYHXxrY+3cqk6TMkYpNr2FeoY3KIr0RPtn9wQ2unlA+GMkRw6+9TFw4YTwDUzx\/JVvARj9KaedXRO8P5B1Du2S32smzqUrcKGEyA+uAgQjKX7zf0boWHGfn71jIKj2689gxp7OAGShNcBUmLMPVjZuiKcA2vuWHHDCQxMCz629kXAIU4ApY15QwggAFbfOP9DhgBJ+nWVJ1AZAfICAj1pAlY6hCADZnveQf7bQIwzVONGJonhLIlS9gr5mFg44Xd+4S3XHoGNPdJl1INIwKyEgHckEhgTe1bGiFY9GSFBYUwLh1IkiJUbY407E7syBSFxKTszEoiE\/YdrgCEayDmtaJwCI9uu8TKMuZSVfSa4BpGgzvomBR\/INhLGzrqDotp01ZR8pn\/1L0JN9d9XNyx0AAAAAElFTkSuQmCC","canUser":{"general":false,"advanced":false,"snippet":false,"social":false,"analysis":false,"analytics":false,"content_ai":false},"showKeywordIntent":true,"isPro":false,"is_front_page":false,"trendsUpgradeLink":"https:\/\/rankmath.com\/pricing\/?utm_source=Plugin&utm_medium=CE%20General%20Tab%20Trends&utm_campaign=WP","trendsUpgradeLabel":"Upgrade","trendsPreviewImage":"https:\/\/nbaem.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/trends-preview.jpg","currentEditor":false,"homepageData":{"assessor":{"powerWords":[],"diacritics":true,"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasBreadcrumb":true,"serpData":{"title":"%sitename% %page% %sep% %sitedesc%","description":"","titleTemplate":"%sitename% %page% %sep% %sitedesc%","descriptionTemplate":"","focusKeywords":"","breadcrumbTitle":"Home","robots":{"index":true},"advancedRobots":[],"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":""}}},"tocTitle":"Table of Contents","tocExcludeHeadings":[],"listStyle":"ul"},"_links":{"self":[{"href":"https:\/\/nbaem.com\/th\/wp-json\/wp\/v2\/pages\/2434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nbaem.com\/th\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nbaem.com\/th\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nbaem.com\/th\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nbaem.com\/th\/wp-json\/wp\/v2\/comments?post=2434"}],"version-history":[{"count":16,"href":"https:\/\/nbaem.com\/th\/wp-json\/wp\/v2\/pages\/2434\/revisions"}],"predecessor-version":[{"id":2675,"href":"https:\/\/nbaem.com\/th\/wp-json\/wp\/v2\/pages\/2434\/revisions\/2675"}],"wp:attachment":[{"href":"https:\/\/nbaem.com\/th\/wp-json\/wp\/v2\/media?parent=2434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}